{"id":1097,"date":"2018-08-30T10:20:25","date_gmt":"2018-08-30T08:20:25","guid":{"rendered":"https:\/\/epilepsiarussi.com\/blog\/?p=1097"},"modified":"2018-07-30T14:46:46","modified_gmt":"2018-07-30T12:46:46","slug":"el-sindrome-de-west-un-tipo-de-epilepsia-rara","status":"publish","type":"post","link":"https:\/\/www.epilepsiarussi.com\/blog\/el-sindrome-de-west-un-tipo-de-epilepsia-rara\/","title":{"rendered":"El S\u00edndrome de West: un tipo de epilepsia rara"},"content":{"rendered":"<h2><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-large wp-image-181\" src=\"http:\/\/epilepsiarussi.com\/blog\/wp-content\/uploads\/2015\/05\/west-1024x814.jpg\" alt=\"west\" width=\"584\" height=\"464\" srcset=\"https:\/\/www.epilepsiarussi.com\/blog\/wp-content\/uploads\/2015\/05\/west-1024x814.jpg 1024w, https:\/\/www.epilepsiarussi.com\/blog\/wp-content\/uploads\/2015\/05\/west-300x239.jpg 300w, https:\/\/www.epilepsiarussi.com\/blog\/wp-content\/uploads\/2015\/05\/west-377x300.jpg 377w, https:\/\/www.epilepsiarussi.com\/blog\/wp-content\/uploads\/2015\/05\/west.jpg 1318w\" sizes=\"(max-width: 584px) 100vw, 584px\" \/><\/h2>\n<h2>El s\u00edndrome de West es un tipo de encefalopat\u00eda epil\u00e9ptica que se manifiesta durante los primeros meses de la infancia.<\/h2>\n<p><!--more--><\/p>\n<p><strong>Este s\u00edndrome afecta tan solo a 1 de cada 4.000 o 6.000 ni\u00f1os (mayoritariamente varones)<\/strong>, por lo que se categoriza como un tipo de patolog\u00eda rara. Se caracteriza por la presencia de tres elementos que se pueden presentar en su totalidad o de forma individual: espasmos epil\u00e9pticos, retraso del desarrollo psicomotor, y un electroencefalograma con hipsarritmia, es decir, con un patr\u00f3n anormal.<\/p>\n<p>Los <strong>s\u00edntomas<\/strong> del S\u00edndrome de West incluyen <strong>espasmos epil\u00e9pticos, retraso psicomotor, como la p\u00e9rdida de las habilidades b\u00e1sicas adquiridas por ni\u00f1os en esa etapa de desarrollo y disfunciones neurol\u00f3gicas<\/strong>. Otros factores que puede desencadenar este s\u00edndrome son la p\u00e9rdida del sentido del humor, el infante presenta indiferencia ante est\u00edmulos sensoriales y desarrollan mayor irritabilidad, lloros sin motivo y p\u00e9rdida de sue\u00f1o. Por \u00faltimo se aprecian alteraciones en el EGG del beb\u00e9, que como ya hemos dicho presenta un electroencefalograma con hisparritmia.<\/p>\n<p><strong>Las causas del s\u00edndrome pueden ser tanto de tipo perinatales como postnatales,<\/strong> y van desde la displasia cerebral, a trastornos cromos\u00f3micos, infecciones, hipoxia e isquemia hasta hemorragias o traumatismos.<\/p>\n<p>A pesar de que en los \u00faltimos a\u00f1os el conocimiento de este s\u00edndrome ha mejorado, <strong>a d\u00eda de hoy sigue sin haber gran especializaci\u00f3n en este campo y algunos casos han llegado a ser detectados de forma tard\u00eda debido a malinterpretaciones del pediatra. Por ello es importante acudir a un especialista para un temprano y correcto diagn\u00f3stico que ayudar\u00e1 notablemente a controlar el desarrollo de la patolog\u00eda.<\/strong><\/p>\n<p>No podemos dejar de investigar enfermedades como estas que constituyen una gran afectaci\u00f3n a la vida de quienes lo sufren, hay que seguir luchando y estudiando estos campos para asegurar que alg\u00fan d\u00eda, esperemos cercano, hallemos una cura que consiga un final feliz para los afectados.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El s\u00edndrome de West es un tipo de encefalopat\u00eda epil\u00e9ptica que se manifiesta durante los primeros meses de la infancia.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[66,212,211,183,318,216],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.14 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El S\u00edndrome de West: un tipo de epilepsia rara &mdash; Viviendo con epilepsia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.epilepsiarussi.com\/blog\/el-sindrome-de-west-un-tipo-de-epilepsia-rara\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El S\u00edndrome de West: un tipo de epilepsia rara &mdash; Viviendo con epilepsia\" \/>\n<meta property=\"og:description\" content=\"El s\u00edndrome de West es un tipo de encefalopat\u00eda epil\u00e9ptica que se manifiesta durante los primeros meses de la infancia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.epilepsiarussi.com\/blog\/el-sindrome-de-west-un-tipo-de-epilepsia-rara\/\" \/>\n<meta property=\"og:site_name\" content=\"Viviendo con epilepsia\" \/>\n<meta property=\"article:published_time\" content=\"2018-08-30T08:20:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-07-30T12:46:46+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/epilepsiarussi.com\/blog\/wp-content\/uploads\/2015\/05\/west-1024x814.jpg\" \/>\n<meta name=\"author\" content=\"epilepsiarussi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"epilepsiarussi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.epilepsiarussi.com\/blog\/el-sindrome-de-west-un-tipo-de-epilepsia-rara\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.epilepsiarussi.com\/blog\/el-sindrome-de-west-un-tipo-de-epilepsia-rara\/\"},\"author\":{\"name\":\"epilepsiarussi\",\"@id\":\"https:\/\/www.epilepsiarussi.com\/blog\/#\/schema\/person\/530d3d7be364ba6c527448a310bc8b43\"},\"headline\":\"El S\u00edndrome de West: un tipo de epilepsia rara\",\"datePublished\":\"2018-08-30T08:20:25+00:00\",\"dateModified\":\"2018-07-30T12:46:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.epilepsiarussi.com\/blog\/el-sindrome-de-west-un-tipo-de-epilepsia-rara\/\"},\"wordCount\":346,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\/\/www.epilepsiarussi.com\/blog\/#organization\"},\"keywords\":[\"diagnostico epilepsia\",\"encefalopat\u00eda epil\u00e9ptica\",\"epilepsias raras\",\"pruebas diagn\u00f3sticas de epilepsia\",\"S\u00edndrome de West\",\"West syndrome\"],\"articleSection\":[\"S\u00edndrome de West\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.epilepsiarussi.com\/blog\/el-sindrome-de-west-un-tipo-de-epilepsia-rara\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.epilepsiarussi.com\/blog\/el-sindrome-de-west-un-tipo-de-epilepsia-rara\/\",\"url\":\"https:\/\/www.epilepsiarussi.com\/blog\/el-sindrome-de-west-un-tipo-de-epilepsia-rara\/\",\"name\":\"El S\u00edndrome de West: un tipo de epilepsia rara &mdash; Viviendo con epilepsia\",\"isPartOf\":{\"@id\":\"https:\/\/www.epilepsiarussi.com\/blog\/#website\"},\"datePublished\":\"2018-08-30T08:20:25+00:00\",\"dateModified\":\"2018-07-30T12:46:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.epilepsiarussi.com\/blog\/el-sindrome-de-west-un-tipo-de-epilepsia-rara\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.epilepsiarussi.com\/blog\/el-sindrome-de-west-un-tipo-de-epilepsia-rara\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.epilepsiarussi.com\/blog\/el-sindrome-de-west-un-tipo-de-epilepsia-rara\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.epilepsiarussi.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El S\u00edndrome de West: un tipo de epilepsia rara\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.epilepsiarussi.com\/blog\/#website\",\"url\":\"https:\/\/www.epilepsiarussi.com\/blog\/\",\"name\":\"Viviendo con epilepsia\",\"description\":\"Blog del centro Epilepsia Russi\",\"publisher\":{\"@id\":\"https:\/\/www.epilepsiarussi.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.epilepsiarussi.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.epilepsiarussi.com\/blog\/#organization\",\"name\":\"Epilepsia Russi Institut del Dr. Antonio Russi\",\"url\":\"https:\/\/www.epilepsiarussi.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.epilepsiarussi.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/epilepsiarussi.com\/blog\/wp-content\/uploads\/2021\/01\/logo.png\",\"contentUrl\":\"https:\/\/epilepsiarussi.com\/blog\/wp-content\/uploads\/2021\/01\/logo.png\",\"width\":706,\"height\":114,\"caption\":\"Epilepsia Russi Institut del Dr. Antonio Russi\"},\"image\":{\"@id\":\"https:\/\/www.epilepsiarussi.com\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.epilepsiarussi.com\/blog\/#\/schema\/person\/530d3d7be364ba6c527448a310bc8b43\",\"name\":\"epilepsiarussi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.epilepsiarussi.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/76cf222d2706d85602f193d36e951f83?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/76cf222d2706d85602f193d36e951f83?s=96&d=mm&r=g\",\"caption\":\"epilepsiarussi\"},\"url\":\"https:\/\/www.epilepsiarussi.com\/blog\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El S\u00edndrome de West: un tipo de epilepsia rara &mdash; Viviendo con epilepsia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.epilepsiarussi.com\/blog\/el-sindrome-de-west-un-tipo-de-epilepsia-rara\/","og_locale":"es_ES","og_type":"article","og_title":"El S\u00edndrome de West: un tipo de epilepsia rara &mdash; Viviendo con epilepsia","og_description":"El s\u00edndrome de West es un tipo de encefalopat\u00eda epil\u00e9ptica que se manifiesta durante los primeros meses de la infancia.","og_url":"https:\/\/www.epilepsiarussi.com\/blog\/el-sindrome-de-west-un-tipo-de-epilepsia-rara\/","og_site_name":"Viviendo con epilepsia","article_published_time":"2018-08-30T08:20:25+00:00","article_modified_time":"2018-07-30T12:46:46+00:00","og_image":[{"url":"http:\/\/epilepsiarussi.com\/blog\/wp-content\/uploads\/2015\/05\/west-1024x814.jpg"}],"author":"epilepsiarussi","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"epilepsiarussi","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.epilepsiarussi.com\/blog\/el-sindrome-de-west-un-tipo-de-epilepsia-rara\/#article","isPartOf":{"@id":"https:\/\/www.epilepsiarussi.com\/blog\/el-sindrome-de-west-un-tipo-de-epilepsia-rara\/"},"author":{"name":"epilepsiarussi","@id":"https:\/\/www.epilepsiarussi.com\/blog\/#\/schema\/person\/530d3d7be364ba6c527448a310bc8b43"},"headline":"El S\u00edndrome de West: un tipo de epilepsia rara","datePublished":"2018-08-30T08:20:25+00:00","dateModified":"2018-07-30T12:46:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.epilepsiarussi.com\/blog\/el-sindrome-de-west-un-tipo-de-epilepsia-rara\/"},"wordCount":346,"commentCount":1,"publisher":{"@id":"https:\/\/www.epilepsiarussi.com\/blog\/#organization"},"keywords":["diagnostico epilepsia","encefalopat\u00eda epil\u00e9ptica","epilepsias raras","pruebas diagn\u00f3sticas de epilepsia","S\u00edndrome de West","West syndrome"],"articleSection":["S\u00edndrome de West"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.epilepsiarussi.com\/blog\/el-sindrome-de-west-un-tipo-de-epilepsia-rara\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.epilepsiarussi.com\/blog\/el-sindrome-de-west-un-tipo-de-epilepsia-rara\/","url":"https:\/\/www.epilepsiarussi.com\/blog\/el-sindrome-de-west-un-tipo-de-epilepsia-rara\/","name":"El S\u00edndrome de West: un tipo de epilepsia rara &mdash; Viviendo con epilepsia","isPartOf":{"@id":"https:\/\/www.epilepsiarussi.com\/blog\/#website"},"datePublished":"2018-08-30T08:20:25+00:00","dateModified":"2018-07-30T12:46:46+00:00","breadcrumb":{"@id":"https:\/\/www.epilepsiarussi.com\/blog\/el-sindrome-de-west-un-tipo-de-epilepsia-rara\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.epilepsiarussi.com\/blog\/el-sindrome-de-west-un-tipo-de-epilepsia-rara\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.epilepsiarussi.com\/blog\/el-sindrome-de-west-un-tipo-de-epilepsia-rara\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.epilepsiarussi.com\/blog\/"},{"@type":"ListItem","position":2,"name":"El S\u00edndrome de West: un tipo de epilepsia rara"}]},{"@type":"WebSite","@id":"https:\/\/www.epilepsiarussi.com\/blog\/#website","url":"https:\/\/www.epilepsiarussi.com\/blog\/","name":"Viviendo con epilepsia","description":"Blog del centro Epilepsia Russi","publisher":{"@id":"https:\/\/www.epilepsiarussi.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.epilepsiarussi.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.epilepsiarussi.com\/blog\/#organization","name":"Epilepsia Russi Institut del Dr. Antonio Russi","url":"https:\/\/www.epilepsiarussi.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.epilepsiarussi.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/epilepsiarussi.com\/blog\/wp-content\/uploads\/2021\/01\/logo.png","contentUrl":"https:\/\/epilepsiarussi.com\/blog\/wp-content\/uploads\/2021\/01\/logo.png","width":706,"height":114,"caption":"Epilepsia Russi Institut del Dr. Antonio Russi"},"image":{"@id":"https:\/\/www.epilepsiarussi.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.epilepsiarussi.com\/blog\/#\/schema\/person\/530d3d7be364ba6c527448a310bc8b43","name":"epilepsiarussi","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.epilepsiarussi.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/76cf222d2706d85602f193d36e951f83?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/76cf222d2706d85602f193d36e951f83?s=96&d=mm&r=g","caption":"epilepsiarussi"},"url":"https:\/\/www.epilepsiarussi.com\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.epilepsiarussi.com\/blog\/wp-json\/wp\/v2\/posts\/1097"}],"collection":[{"href":"https:\/\/www.epilepsiarussi.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.epilepsiarussi.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.epilepsiarussi.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.epilepsiarussi.com\/blog\/wp-json\/wp\/v2\/comments?post=1097"}],"version-history":[{"count":1,"href":"https:\/\/www.epilepsiarussi.com\/blog\/wp-json\/wp\/v2\/posts\/1097\/revisions"}],"predecessor-version":[{"id":1098,"href":"https:\/\/www.epilepsiarussi.com\/blog\/wp-json\/wp\/v2\/posts\/1097\/revisions\/1098"}],"wp:attachment":[{"href":"https:\/\/www.epilepsiarussi.com\/blog\/wp-json\/wp\/v2\/media?parent=1097"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.epilepsiarussi.com\/blog\/wp-json\/wp\/v2\/categories?post=1097"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.epilepsiarussi.com\/blog\/wp-json\/wp\/v2\/tags?post=1097"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}